{"id":44760,"date":"2021-09-29T13:56:21","date_gmt":"2021-09-29T11:56:21","guid":{"rendered":"https:\/\/www.esteri.it\/?page_id=44760"},"modified":"2026-01-02T14:51:11","modified_gmt":"2026-01-02T13:51:11","slug":"infomercatiesteri-osservatorio-economico","status":"publish","type":"page","link":"https:\/\/www.esteri.it\/en\/temi\/diplomaziaeconomica\/strumenti-e-servizi-informativi-per-le-imprese\/infomercatiesteri-osservatorio-economico\/","title":{"rendered":"InfoMercatiEsteri\/Osservatorio Economico"},"content":{"rendered":"<p><strong>infoMercatiEsteri<\/strong>\u00a0\u00e8 lo strumento di\u00a0<i>business intelligence\u00a0<\/i>realizzato dalla Farnesina per soddisfare la domanda\u00a0di informazioni sui mercati esteri proveniente dagli operatori economici nazionali.<\/p>\n<p>Grazie al costante lavoro di analisi delle Ambasciate e dei Consolati, in collaborazione con le Unit\u00e0 dell\u2019Agenzia ICE in essi integrate, e ai contributi dell\u2019ENIT e di Assocamerestero, infoMercatiEsteri mette a disposizione del sistema produttivo italiano uno strumento ricco di informazioni utili per le scelte di internazionalizzazione.<\/p>\n<p>Utilizzando un doppio percorso di ricerca, per paesi e per settori, gli operatori economici nazionali avranno acesso ad un&#8217;ampia gamma di informazioni su: outlook economico e politico, opportunit\u00e0 di mercato e possibilit\u00e0 di partnership con aziende locali e\/o italiane, iniziative promozionali, ostacoli agli scambi, criticit\u00e0 negli investimenti e possibili rischi, accesso al credito, quadro delle presenze italiane e dei rapporti bilaterali.<\/p>\n<p>Da dicembre 2020, la piattaforma si arricchisce di nuovi contenuti informativi prodotti dall\u2019Osservatorio Economico sul Commercio Estero del Maeci riguardanti: analisi statistiche, schede di sintesi su mercati e aree geografiche e sull\u2019andamento del commercio estero dell\u2019Italia con il resto del mondo sia a livello nazionale sia regionale, oltre ad alcuni approfondimenti settoriali che fotografano la performance italiana in circa 35 categorie merceologiche.<\/p>\n<p>Una vera e propria piattaforma unica integrata al servizio delle imprese interessate ai mercati esteri.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>L&#8217;Osservatorio Economico, istituito con legge n.304 del 20 ottobre 1990, raccoglie, studia ed elabora i dati in materia di internazionalizzazione, mettendo a disposizione dell&#8217;utenza una serie di pubblicazioni quali:<\/strong><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong><a href=\"https:\/\/www.infomercatiesteri.it\/osservatorio-economico-interscambio-commerciale-italiano-mondo.php\">Interscambio commerciale italiano con il resto del mondo<\/a><br \/>\n<\/strong>Sezione dedicata alle statistiche concernenti l\u2019interscambio commerciale italiano con il resto del mondo, nonch\u00e9 la sua composizione geografica, settoriale e territoriale.<\/li>\n<li><strong><a href=\"https:\/\/www.infomercatiesteri.it\/osservatorio-economico-schede-di-sintesi-sui-paesi.php\">Schede di sintesi sui paesi<\/a><br \/>\n<\/strong>In questa sezione si trovano brevi elaborati statistici concernenti i principali indicatori macroeconomici nonch\u00e9 i dati sugli scambi con l&#8217;estero del paese in esame, evidenziando, in particolare, i rapporti con l&#8217;Italia.<\/li>\n<li><strong><a href=\"https:\/\/www.infomercatiesteri.it\/osservatorio-economico-commercio-estero.php\" rel=\"alternate\">Commento ai dati di commercio estero<br \/>\n<\/a><\/strong>Sezione dedicata ai dati diffusi periodicamente dall&#8217;Istat in materia di commercio estero dell&#8217;Italia.<\/li>\n<li><strong><a href=\"https:\/\/www.infomercatiesteri.it\/osservatorio-economico-interscambio-commerciale-italiano-settoriale.php\" rel=\"alternate\">Interscambio commerciale settoriale<br \/>\n<\/a><\/strong>Sezione dedicata all&#8217;interscambio commerciale settoriale dell&#8217;Italia, suddiviso per aree, Paesi di provenienza e destinazione, per ripartizione territoriale nazionale.<\/li>\n<li><strong><a href=\"https:\/\/www.infomercatiesteri.it\/osservatorio-economico-link-utili.php\" rel=\"alternate\">Link Utili<br \/>\n<\/a><\/strong>In questa sezione vengono riportate alcune fonti &#8211; di natura nazionale ed internazionale \u2013 dalle quali si possono trarre informazioni e dati relativi a indicatori macroeconomici e di commercio estero.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>CONTATTI UTILI<\/strong>:<br \/>\nDirezione Generale per la Crescita e la Promozione delle Esportazioni<\/p>\n<p>Unit\u00e0 per le esportazioni<br \/>\n<a href=\"mailto:dgceuniexport@esteri.it\">dgceuniexport@esteri.it<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"infoMercatiEsteri\u00a0\u00e8 lo strumento di\u00a0business intelligence\u00a0realizzato dalla Farnesina per soddisfare la domanda\u00a0di informazioni sui mercati esteri proveniente dagli operatori economici nazionali. Grazie al costante lavoro di analisi delle Ambasciate e dei Consolati, in collaborazione con le Unit\u00e0 dell\u2019Agenzia ICE in essi integrate, e ai contributi dell\u2019ENIT e di Assocamerestero, infoMercatiEsteri mette a disposizione del sistema produttivo [&hellip;]","protected":false},"author":1,"featured_media":0,"parent":30250,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"page-imprese.php","meta":{"footnotes":""},"class_list":["post-44760","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.esteri.it\/en\/wp-json\/wp\/v2\/pages\/44760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esteri.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.esteri.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.esteri.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esteri.it\/en\/wp-json\/wp\/v2\/comments?post=44760"}],"version-history":[{"count":4,"href":"https:\/\/www.esteri.it\/en\/wp-json\/wp\/v2\/pages\/44760\/revisions"}],"predecessor-version":[{"id":168622,"href":"https:\/\/www.esteri.it\/en\/wp-json\/wp\/v2\/pages\/44760\/revisions\/168622"}],"up":[{"embeddable":true,"href":"https:\/\/www.esteri.it\/en\/wp-json\/wp\/v2\/pages\/30250"}],"wp:attachment":[{"href":"https:\/\/www.esteri.it\/en\/wp-json\/wp\/v2\/media?parent=44760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}