{"id":101288,"date":"2023-05-25T16:47:51","date_gmt":"2023-05-25T14:47:51","guid":{"rendered":"https:\/\/www.esteri.it\/?page_id=101288"},"modified":"2023-05-26T14:17:50","modified_gmt":"2023-05-26T12:17:50","slug":"convivenze-di-fatto","status":"publish","type":"page","link":"https:\/\/www.esteri.it\/it\/servizi-opportunita\/italiani-all-estero\/aire_0\/convivenze-di-fatto\/","title":{"rendered":"Convivenze di fatto"},"content":{"rendered":"<p>Il cittadino italiano residente all\u2019estero pu\u00f2 dichiarare presso l\u2019Ufficio consolare competente per residenza, la \u201cconvivenza di fatto\u201d con persona dello stesso sesso o di sesso diverso <strong>residente allo stesso indirizzo estero ed iscritta nello stesso Comune Aire,<\/strong> come precisato dal Ministero dell\u2019Interno.<\/p>\n<p>In seguito alla trasmissione della dichiarazione di \u201cconvivenza di fatto\u201d, il Comune italiano potr\u00e0 rilasciare una certificazione di istituzione di famiglia anagrafica.<\/p>\n<p>Presso l\u2019Ufficio consolare il cittadino italiano residente all\u2019estero, ove in possesso dei requisiti richiesti, pu\u00f2 stipulare il \u201ccontratto di convivenza\u201d previsto dal comma 50 della legge n. 76\/2016 o chiedere l\u2019autenticazione delle sottoscrizioni in calce al contratto stesso. Il contratto di convivenza ha contenuto esclusivamente patrimoniale ed \u00e8 regolato dalla legge italiana solo se i contraenti sono entrambi cittadini italiani o risiedono in Italia: se i due contraenti hanno diversa nazionalit\u00e0 e risiedono in un Paese estero, la legge applicabile sar\u00e0 quella di tale Paese.<\/p>\n","protected":false},"excerpt":{"rendered":"Il cittadino italiano residente all\u2019estero pu\u00f2 dichiarare presso l\u2019Ufficio consolare competente per residenza, la \u201cconvivenza di fatto\u201d con persona dello stesso sesso o di sesso diverso residente allo stesso indirizzo estero ed iscritta nello stesso Comune Aire, come precisato dal Ministero dell\u2019Interno. In seguito alla trasmissione della dichiarazione di \u201cconvivenza di fatto\u201d, il Comune italiano [&hellip;]","protected":false},"author":19,"featured_media":0,"parent":29763,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-101288","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/pages\/101288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=101288"}],"version-history":[{"count":1,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/pages\/101288\/revisions"}],"predecessor-version":[{"id":101289,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/pages\/101288\/revisions\/101289"}],"up":[{"embeddable":true,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/pages\/29763"}],"wp:attachment":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=101288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}