{"id":30252,"date":"2021-07-13T13:04:17","date_gmt":"2021-07-13T11:04:17","guid":{"rendered":"https:\/\/www.esteri.it\/?page_id=30252"},"modified":"2026-01-02T15:02:41","modified_gmt":"2026-01-02T14:02:41","slug":"promozione-integrata-del-sistema","status":"publish","type":"page","link":"https:\/\/www.esteri.it\/it\/temi\/diplomaziaeconomica\/promozione-integrata-del-sistema\/","title":{"rendered":"Promozione integrata dell&#8217;Italia"},"content":{"rendered":"<p>La Direzione Generale per la Crescita e la Promozione delle Esportazioni coordina le attivit\u00e0 di promozione dell\u2019Italia, in stretto raccordo con partner pubblici e privati e con le diverse articolazioni del Sistema Italia, per promuovere la crescita del Paese e l\u2019internazionalizzazione delle imprese italiane. La promozione delle eccellenze italiane nel mondo racconta l\u2019essere e il saper fare italiani, con l\u2019obiettivo di presentare al pubblico internazionale i valori, i talenti, la sapienza, la bellezza, la variet\u00e0, l\u2019originalit\u00e0 e la spinta all\u2019innovazione che caratterizzano da sempre i diversi aspetti dell\u2019essere e del saper fare italiani nei campi della cultura, dell\u2019economia, della scienza e della tecnologia. La narrazione di un Paese plurale, operoso, resiliente, forte del suo passato e orientato al futuro.<\/p>\n<p>Ogni iniziativa nasce a partire da un tema che viene sviluppato e declinato nelle diverse dimensioni che lo compongono, con linguaggi e strumenti diversi. Il risultato \u00e8 l\u2019ideazione e produzione di contenuti originali per il pubblico internazionale da divulgare in svariate modalit\u00e0, che spaziano dalle mostre esperienziali, ai prodotti audio-visivi, alla produzione editoriale, al gaming. Dal 2020 abbiamo prodotto oltre 100 progetti originali con il contributo di pi\u00f9 di 400 attori tra aziende, associazioni, enti locali, artisti e creativi, dando vita ad oltre 20.000 eventi in tutto il mondo.<\/p>\n<p>La Direzione Generale inoltre accompagna e promuove, in una logica integrata, i grandi eventi internazionali che si svolgono in Italia, utilizzandoli quali leve preziose per la valorizzazione dell\u2019Italia.<\/p>\n<p>&nbsp;<\/p>\n<p>LE RASSEGNE TEMATICHE: MODA, DESIGN, MADE IN ITALY, ALTA CUCINA, SPAZIO, RICERCA E SPORT<\/p>\n<ul>\n<li><strong><a href=\"https:\/\/italiandesignday-official.it\/\">Giornata del Design italiano nel mondo:<\/a><\/strong>\u00a0rassegna annuale, lanciata nel 2017 dalla Direzione, in collaborazione e con il sostegno del Ministero della Cultura, per la promozione e internazionalizzazione di un comparto strategico per l\u2019export italiano.<\/li>\n<li><strong>Giornata della Ricerca italiana nel mondo<\/strong>: istituita in occasione del 15 aprile, anniversario della nascita del genio italiano Leonardo Da Vinci, la rassegna mira a valorizzare il contributo dei ricercatori italiani alla scienza internazionale e promuovere la divulgazione dei risultati delle loro ricerche. La prima edizione \u00e8 stata lanciata nel 2018 dal Ministero degli Affari Esteri e della Cooperazione Internazionale, dal Ministero dell\u2019Istruzione, dell\u2019Universit\u00e0 e della Ricerca e dal Ministero della Salute.<\/li>\n<li><strong>Settimana della Cucina italiana nel mondo<\/strong>: ogni anno, dal 2016 la Direzione organizza la Settimana della Cucina italiana nel Mondo, un\u2019occasione per valorizzare le eccellenze enogastronomiche italiane, la dieta mediterranea e l\u2019innovazione scientifica in materia di agroalimentare, oltre che per contrastare il fenomeno dell\u2019Italian sounding.<\/li>\n<li><strong>Giornata Nazionale dello Spazio<\/strong>: istituita nel 2021 per celebrare il lancio del primo satellite italiano, il San Marco 1, decollato nel 1964 dalla base americana di Wallops Island. La rassegna si propone di raccontare come la scienza e la tecnologia applicate allo spazio contribuiscano al miglioramento della condizione umana e come il settore offra ritorni in termini di crescita economica, benessere, sviluppo sostenibile e protezione ambientale.<\/li>\n<li>La <strong>giornata dello sport italiano nel mondo<\/strong>: da realizzarsi nella seconda settimana di settembre e che, a partire dal 2024 sar\u00e0 l\u2019occasione per raccontare, attraverso lo sport ed i suoi protagonisti, le eccellenze, i distretti, le industrie italiane di settore, nonch\u00e9 valorizzare i giovani e le collettivit\u00e0 italiane.<\/li>\n<li>Le <strong>Giornate della moda italiana nel mondo<\/strong>: rassegna lanciata nel gennaio 2025 per promuovere la moda italiana a livello internazionale, con eventi programmati in diverse citt\u00e0 del mondo. Realizzate in collaborazione con ICE Agenzia e varie associazioni di categoria del settore moda, le GMIM si pongono l&#8217;obiettivo di valorizzare la produzione italiana e sostenere l&#8217;internazionalizzazione delle imprese del settore.<\/li>\n<li><a href=\"https:\/\/www.mimit.gov.it\/it\/made-in-italy\"><strong>Giornata Nazionale del Made in Italy<\/strong><\/a>: promossa del Ministero delle Imprese e del Made in Italy, celebra l\u2019eccellenza dei prodotti italiani, dalla moda all\u2019enogastronomia, dall\u2019artigianato al design. La Rete delle Ambasciate, dei Consolati e degli Istituti Italiani di cultura contribuisce alle celebrazioni organizzando all\u2019estero eventi per valorizzare la creativit\u00e0, la qualit\u00e0 e l\u2019innovazione del nostro Paese nel mondo.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>LE INIZIATIVE IN CORSO<\/p>\n<ul>\n<li>\u201c<strong>Crescita<\/strong>\u201d: struttura immersiva e interattiva pensata per raccontare l\u2019export italiano in modo semplice e coinvolgente. Si descrivono strategie e strumenti per l\u2019internazionalizzazione del Sistema Italia.<\/li>\n<li>\u201c<strong>Distretti industriali, valori italiani. Il ritmo del Made in Italy<\/strong>\u201d: sei video-racconti che descrivono i pi\u00f9 importanti Distretti Industriali Italiani attraverso i valori fondamentali del Made in Italy: stile, innovazione, patrimonio, passione, famiglia, variet\u00e0.<\/li>\n<li>\u201c<strong>Il gusto del benessere, tre men\u00f9 italiani<\/strong>\u201d: 10 video-ricette ispirate alla tradizione culinaria italiana, rivisitate in chiave leggera, che raccontano come la scelta consapevole degli ingredienti possa migliorare la qualit\u00e0 della vita. Realizzato con Giallo Zafferano<\/li>\n<li>\u201c<strong>Italia \u00e8 moda<\/strong>\u201d: progetto filmico immersivo realizzato con Realt\u00e0 Virtuale (VR), concepito per comunicare in modo emozionale i valori di eccellenza della moda italiana. Fruibile con l\u2019utilizzo di visori.<\/li>\n<li>\u201c<strong>CostumItaly<\/strong>\u201d: documentario che racconta il mestiere del costumista attraverso le storie dei grandi professionisti italiani del passato, di quelli tuttora in attivit\u00e0 in Italia e all\u2019estero, e delle grandi sartorie che lavorano per il mondo dell\u2019audiovisivo e per il teatro.<\/li>\n<li>\u201c<strong>Ideas<\/strong>\u201d: webserie originale, giunta alla sua terza stagione, che racconta l\u2019Italia di oggi, dando voce a storie di innovazione imprenditoriale, creativit\u00e0, rispetto dell\u2019ambiente, inclusione sociale.<\/li>\n<li>\u201c<strong> An Italian journey into beauty and personal care<\/strong>\u201d: mostra pannellare e interattiva, un viaggio attraverso l\u2019evoluzione della bellezza e della cura della persona in Italia. Il percorso si snoda dalle radici storiche della cosmetica fino alle pi\u00f9 recenti innovazioni sostenibili.<\/li>\n<li>\u201c<strong>The world of Italian rice<\/strong>\u201d: mostra pannellare e interattiva che propone un focus monografico interamente dedicato al riso italiano, con l\u2019obiettivo di restituirne la profondit\u00e0 storica e la complessit\u00e0 attuale.<\/li>\n<li>\u201c<strong>Audiovisiva<\/strong>\u201d: piattaforma digitale che raccoglie e rende disponibili una selezione dei migliori documentari dedicati ai protagonisti e alle protagoniste della creativit\u00e0 e delle eccellenze italiane, con un catalogo ampio e in costante aggiornamento.<\/li>\n<li>\u201c<strong>Fashion Panorama 2<\/strong>\u201d: mostra pannellare, fotografica e video, curata da Vogue Italia per dar voce alle nuove generazioni di stiliste e stilisti italiani, contribuendo a diffondere nel mondo la loro visione e il loro stile.<\/li>\n<li>\u201c<strong> Donne del progetto grafico italiano. Dalle origini alla contemporaneit\u00e0<\/strong>\u201d: manifesti, libri, bozzetti, disegni, fotografie e video-interviste che mettono in mostra le figure e i contributi di progettiste grafiche donne attive tra gli anni \u201950 del novecento e i giorni nostri in Italia, tra boom economico e nuovi costumi.<\/li>\n<li><strong>\u201cIl gesto semplice di una storia infinita<\/strong>\u201d: mostra, ricettario digitale e ciclo di video realizzati da ALMA \u2013 La Scuola Internazionale di Cucina e dall\u2019Universit\u00e0 di Parma guidano alla scoperta della cucina italiana, da sempre legata a benessere e sostenibilit\u00e0, attraverso gesti e materie prime essenziali.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"La Direzione Generale per la Crescita e la Promozione delle Esportazioni coordina le attivit\u00e0 di promozione dell\u2019Italia, in stretto raccordo con partner pubblici e privati e con le diverse articolazioni del Sistema Italia, per promuovere la crescita del Paese e l\u2019internazionalizzazione delle imprese italiane. La promozione delle eccellenze italiane nel mondo racconta l\u2019essere e il [&hellip;]","protected":false},"author":1,"featured_media":0,"parent":329,"menu_order":7,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-30252","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/pages\/30252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=30252"}],"version-history":[{"count":6,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/pages\/30252\/revisions"}],"predecessor-version":[{"id":168630,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/pages\/30252\/revisions\/168630"}],"up":[{"embeddable":true,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/pages\/329"}],"wp:attachment":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=30252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}