{"id":30998,"date":"2021-07-22T12:44:05","date_gmt":"2021-07-22T10:44:05","guid":{"rendered":"https:\/\/www.esteri.it\/?page_id=30998"},"modified":"2025-12-18T14:49:32","modified_gmt":"2025-12-18T13:49:32","slug":"italia_nazioni_unite_pace_sicurezza","status":"publish","type":"page","link":"https:\/\/www.esteri.it\/it\/temi\/organizzazioni_internazionali\/onu\/italia_nazioni_unite_pace_sicurezza\/","title":{"rendered":"L\u2019azione dell\u2019Italia alle Nazioni Unite. Pace e sicurezza"},"content":{"rendered":"<p>Fin dal suo ingresso nel 1955 l\u2019Italia ha assicurato all\u2019Organizzazione delle Nazioni Unite il massimo sostegno, nel quadro di una scelta a favore del\u00a0<strong>multilateralismo<\/strong>, che rappresenta uno dei punti di riferimento essenziali della nostra azione di politica estera.<\/p>\n<p>Il valore chiave delle Nazioni Unite risiede, in primo luogo, nella\u00a0<strong>vocazione universale<\/strong> dell\u2019Organizzazione, sede di confronto politico tra gli Stati e di ricerca di soluzioni condivise su tematiche globali che riguardano la sicurezza e la stabilit\u00e0 internazionali, la promozione dei diritti umani, lo sviluppo e la tutela ambientale.<\/p>\n<p><strong>L\u2019 Italia \u00e8 il settimo contribuente finanziario delle Nazioni Unite<\/strong>, ed \u00e8 in prima linea nel perseguimento degli obiettivi della Carta ONU, dal mantenimento della pace e della sicurezza internazionale, alla promozione e difesa dei diritti umani, allo sviluppo sostenibile.<\/p>\n<p>L\u2019Italia \u00e8 stata eletta 7 volte (1959-1960, 1971-1972, 1975-1976, 1987-1988, 1995-1996, 2007-2008, 2017)\u00a0 come membro non permanente del Consiglio di Sicurezza. Nell\u2019ultima elezione, che si \u00e8 tenuta nel giugno 2016, a seguito di una campagna pluriennale e competitiva e in una dimostrazione di solidariet\u00e0 europea, l\u2019Italia e i Paesi Bassi hanno deciso di dividere il mandato: l\u2019Italia ha fatto parte del Consiglio di Sicurezza nel 2017 (assumendone la presidenza mensile a novembre), e l\u2019Olanda \u00e8 subentrata il 1 gennaio 2018. In tale ruolo, l\u2019Italia ha portato all\u2019attenzione del massimo organo decisionale onusiano tematiche trasversali e le principali aree geografiche di nostro prioritario interesse, in particolare\u00a0 Mediterraneo, Sahel e Corno d\u2019Africa, le migrazioni di massa, il terrorismo, la protezione dei civili, il contrasto alle violazioni dei diritti umani e del diritto umanitario, la protezione del patrimonio culturale, la gestione degli aspetti ambientali delle operazioni di pace ONU.<\/p>\n<p>L\u2019Italia, inoltre, \u00e8 stata eletta nove volte (1961-1963, 1970-1972, 1974-1982, 1986-1994, 1998-2003, 2004-2006, 2010-2012, 2014-2015, 2016-2018) nel Consiglio Economico e Sociale, di cui \u00e8 attualmente membro per il mandato 2016-2018.<\/p>\n<p>Sul fronte dei diritti umani, l\u2019Italia \u00e8 stata membro del Consiglio Diritti Umani per due mandati (2007 \u2013 2009, 2011 \u2013 2014, 2019 &#8211; 2021), \u00e8 stata rieletta per farne parte nel triennio <strong>2026 &#8211; 2028<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"Fin dal suo ingresso nel 1955 l\u2019Italia ha assicurato all\u2019Organizzazione delle Nazioni Unite il massimo sostegno, nel quadro di una scelta a favore del\u00a0multilateralismo, che rappresenta uno dei punti di riferimento essenziali della nostra azione di politica estera. Il valore chiave delle Nazioni Unite risiede, in primo luogo, nella\u00a0vocazione universale dell\u2019Organizzazione, sede di confronto politico [&hellip;]","protected":false},"author":1,"featured_media":0,"parent":30934,"menu_order":10,"comment_status":"closed","ping_status":"closed","template":"page-estera.php","meta":{"footnotes":""},"class_list":["post-30998","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/pages\/30998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=30998"}],"version-history":[{"count":1,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/pages\/30998\/revisions"}],"predecessor-version":[{"id":165547,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/pages\/30998\/revisions\/165547"}],"up":[{"embeddable":true,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/pages\/30934"}],"wp:attachment":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=30998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}