{"id":61361,"date":"2021-11-02T21:51:44","date_gmt":"2021-11-02T20:51:44","guid":{"rendered":"https:\/\/www.esteri.it\/?page_id=61361"},"modified":"2021-11-02T22:02:49","modified_gmt":"2021-11-02T21:02:49","slug":"decrleg_29_93","status":"publish","type":"page","link":"https:\/\/www.esteri.it\/it\/ministero\/sportello_info\/normativa\/decrleg_29_93\/","title":{"rendered":"Decreto Leg 29\/93"},"content":{"rendered":"<p class=\"titolo\">Decreto Legislativo 3 febbraio 1993 N. 29<\/p>\n<p class=\"sottotitolo\">Razionalizzazione della organizzazione delle Amministrazioni pubbliche e revisione della disciplina in materia di pubblico impiego, a norma dell&#8217;articolo 2 della legge 23 ottobre 1992, n. 421<\/p>\n<p>(in G.U. n. 30 del 6 febbraio 1993 &#8211; suppl. ord. n. 14)<\/p>\n<p>(omissis)<\/p>\n<p>TITOLO II<\/p>\n<p>ORGANIZZAZIONE<\/p>\n<p>Capo I<\/p>\n<p>RELAZIONI CON IL PUBBLICO<\/p>\n<p>Art. 11.<\/p>\n<p>Trasparenza delle amministrazioni pubbliche<\/p>\n<p>1. L\u2019organismo di cui all\u2019articolo 2, comma 1, lettera mm), della legge 23 ottobre 1992, n. 421, ai fini della trasparenza e rapidita\u2019 del procedimento, definisce, ai sensi dell\u2019articolo 5, lettera b), i modelli e sistemi informativi utili alla interconnessione tra le amministrazioni pubbliche.<\/p>\n<p>2. La Presidenza del Consiglio dei Ministri &#8211; Dipartimento della funzione pubblica ed i comitati metropolitani di cui all\u2019articolo 18 del decreto-legge 24 novembre 1990, n. 344, convertito, con modificazioni, dalla legge 23 gennaio 1991, n. 21, promuovono, utilizzando il personale degli uffici di cui all\u2019articolo 12, la costituzione di servizi di accesso polifunzionale alle amministrazioni pubbliche nell\u2019ambito dei progetti finalizzati di cui all\u2019articolo 26 della legge 11 marzo 1988, n. 67 (1).<\/p>\n<p>(1) Le disposizioni di cui al presente articolo sono ora contenute nell\u2019art. 10 del decreto legislativo 30 marzo 2001, n. 165, che si riporta integralmente:<\/p>\n<p>Articolo 10<\/p>\n<p>Trasparenza delle amministrazioni pubbliche<\/p>\n<p>(Art.11 del d.lgs n.29 del 1993, come modificato dall&#8217;art.43, comma 9 del d.lgs n.80 del 1998)<\/p>\n<p>1. L&#8217;organismo di cui all&#8217;articolo 2, comma 1, lettera mm), della legge 23 ottobre 1992, n.421, ai fini della trasparenza e rapidita&#8217; del procedimento, definisce, ai sensi dell&#8217;articolo 2, comma 1, lettera c), i modelli e sistemi informativi utili alla interconnessione tra le amministrazioni pubbliche.<\/p>\n<p>2. La Presidenza del Consiglio dei ministri &#8211; Dipartimento della funzione pubblica ed i comitati metropolitani di cui all&#8217;articolo 18 del decreto-legge 24 novembre 1990, n. 344, convertito, con modificazioni, dalla legge 23 gennaio 1991, n. 21, promuovono, utilizzando il personale degli uffici di cui all&#8217;articolo 11, la costituzione di servizi di accesso polifunzionale alle amministrazioni pubbliche nell&#8217;ambito dei progetti finalizzati di cui all&#8217;articolo 26 della legge 11 marzo 1988, n. 67, e successive modificazioni ed integrazioni.<\/p>\n<p>Art. 12.<\/p>\n<p>Ufficio relazioni con il pubblico<\/p>\n<p>1. Le amministrazioni pubbliche, al fine di garantire la piena attuazione della legge 7 agosto 1990, n. 241, individuano, nell\u2019ambito della propria struttura e nel contesto della ridefinizione degli uffici di cui all\u2019articolo 31, uffici per le relazioni con il pubblico.<\/p>\n<p>2. Gli uffici per le relazioni con il pubblico provvedono, anche mediante l\u2019utilizzo di tecnologie informatiche:<\/p>\n<p>a) al servizio all\u2019utenza per i diritti di partecipazione di cui al capo III della legge 7 agosto 1990, n. 241;<\/p>\n<p>b) all\u2019informazione all\u2019utenza relativa agli atti e allo stato dei procedimenti;<\/p>\n<p>c) alla ricerca ed analisi finalizzate alla formulazione di proposte alla propria amministrazione sugli aspetti organizzativi e logistici del rapporto con l\u2019utenza.<\/p>\n<p>3. Agli uffici per le relazioni con il pubblico viene assegnato, nell\u2019ambito delle attuali dotazioni organiche delle singole amministrazioni, personale con idonea qualificazione e con elevata capacita\u2019 di avere contatti con il pubblico, eventualmente assicurato da apposita formazione.<\/p>\n<p>4. Al fine di assicurare la conoscenza di normative, servizi e strutture, le amministrazioni pubbliche programmano ed attuano iniziative di comunicazione di pubblica utilita\u2019; in particolare, le amministrazioni dello Stato, per l\u2019attuazione delle iniziative individuate nell\u2019ambito delle proprie competenze, si avvalgono del Dipartimento per l\u2019informazione e l\u2019editoria della Presidenza del Consiglio dei Ministri quale struttura centrale di servizio, secondo un piano annuale di coordinamento del fabbisogno di prodotti e servizi, da sottoporre all\u2019approvazione del Presidente del Consiglio dei Ministri (2).<\/p>\n<p>(omissis)<\/p>\n<p>(2) Le disposizioni di cui al presente articolo sono ora contenute nell\u2019art. 11 del decreto legislativo 30 marzo 2001, n. 165, che si riporta integralmente:<\/p>\n<p>Articolo 11<\/p>\n<p>Ufficio relazioni con il pubblico<\/p>\n<p>(Art.l2, commi da 1 a 5-ter del d.lgs n.29 del 1993, come sostituiti dall&#8217;art.7 del d.lgs n.546 del 1993 e successivamente modificati dall&#8217;art.3 del decreto legge n.163 del 1995, convertito con modificazioni dalla legge n.273 del 1995)<\/p>\n<p>1. Le amministrazioni pubbliche, al fine di garantire la piena attuazione della legge 7 agosto 1990, n. 241, e successive modificazioni ed integrazioni, individuano, nell&#8217;ambito della propria struttura uffici per le relazioni con il pubblico.<\/p>\n<p>2. Gli uffici per le relazioni con il pubblico provvedono, anche mediante l&#8217;utilizzo di tecnologie informatiche:<\/p>\n<p>a) al servizio all&#8217;utenza per i diritti di partecipazione di cui al capo III della legge 7 agosto 1990, n. 241, e successive modificazioni ed integrazioni;<br \/>\nb) all&#8217;informazione all&#8217;utenza relativa agli atti e allo stato dei procedimenti;<\/p>\n<p>c) alla ricerca ed analisi finalizzate alla formulazione di proposte alla propria amministrazione sugli aspetti organizzativi e logistici del rapporto con l&#8217;utenza.<\/p>\n<p>3. Agli uffici per le relazioni con il pubblico viene assegnato, nell&#8217;ambito delle attuali dotazioni organiche delle singole amministrazioni, personale con idonea qualificazione e con elevata capacita&#8217; di avere contatti con il pubblico, eventualmente assicurato da apposita formazione.<\/p>\n<p>4. Al fine di assicurare la conoscenza di normative, servizi e strutture, le amministrazioni pubbliche programmano ed attuano iniziative di comunicazione di pubblica utilita&#8217;; in particolare, le amministrazioni dello Stato, per l&#8217;attuazione delle iniziative individuate nell&#8217;ambito delle proprie competenze, si avvalgono del Dipartimento per l&#8217;informazione e l&#8217;editoria della Presidenza del Consiglio dei ministri quale struttura centrale di servizio, secondo un piano annuale di coordinamento del fabbisogno di prodotti e servizi, da sottopone all&#8217;approvazione del Presidente del Consiglio dei Ministri.<\/p>\n<p>5. Per le comunicazioni previste dalla legge 7 agosto 1990, n. 241, e successive modificazioni ed integrazioni, non si applicano le norme vigenti che dispongono la tassa a carico del destinatario.<\/p>\n<p>6. Il responsabile dell&#8217;ufficio per le relazioni con il pubblico e il personale da lui indicato possono promuovere iniziative volte, anche con il supporto delle procedure informatiche, al miglioramento dei servizi per il pubblico, alla semplificazione e all&#8217;accelerazione delle procedure e all&#8217;incremento delle modalita&#8217; di accesso informale alle informazioni in possesso dell&#8217;amministrazione e ai documenti amministrativi.<\/p>\n<p>7. L&#8217;organo di vertice della gestione dell&#8217;amministrazione o dell&#8217;ente verifica l&#8217;efficacia dell&#8217;applicazione delle iniziative di cui al comma 6, ai fini dell&#8217;inserimento della verifica positiva nel fascicolo personale del dipendente. Tale riconoscimento costituisce titolo autonomamente valutabile in concorsi pubblici e nella progressione di&#8217; carriera del dipendente. Gli organi di vertice trasmettono le iniziative riconosciute ai sensi del presente comma al Dipartimento della funzione pubblica, ai fini di un&#8217;adeguata pubblicizzazione delle stesse. Il Dipartimento annualmente individua le forme di pubblicazione.<\/p>\n","protected":false},"excerpt":{"rendered":"Decreto Legislativo 3 febbraio 1993 N. 29 Razionalizzazione della organizzazione delle Amministrazioni pubbliche e revisione della disciplina in materia di pubblico impiego, a norma dell&#8217;articolo 2 della legge 23 ottobre 1992, n. 421 (in G.U. n. 30 del 6 febbraio 1993 &#8211; suppl. ord. n. 14) (omissis) TITOLO II ORGANIZZAZIONE Capo I RELAZIONI CON IL [&hellip;]","protected":false},"author":4,"featured_media":0,"parent":61355,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-61361","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/pages\/61361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=61361"}],"version-history":[{"count":1,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/pages\/61361\/revisions"}],"predecessor-version":[{"id":61367,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/pages\/61361\/revisions\/61367"}],"up":[{"embeddable":true,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/pages\/61355"}],"wp:attachment":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=61361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}