{"id":203367,"date":"2026-09-02T14:05:30","date_gmt":"2026-09-02T12:05:30","guid":{"rendered":"https:\/\/www.esteri.it\/?p=203367"},"modified":"2026-09-02T15:01:40","modified_gmt":"2026-09-02T13:01:40","slug":"il-vice-ministro-cirielli-incontra-una-delegazione-del-senato-giapponese","status":"publish","type":"post","link":"https:\/\/www.esteri.it\/it\/sala_stampa\/archivionotizie\/comunicati\/2026\/09\/il-vice-ministro-cirielli-incontra-una-delegazione-del-senato-giapponese\/","title":{"rendered":"Il Vice Ministro Cirielli incontra una delegazione del Senato giapponese"},"content":{"rendered":"<p>Il Vice Ministro degli Esteri Edmondo Cirielli ha ricevuto oggi alla Farnesina una delegazione del Senato giapponese guidata dal Sen. Aoki Kazuhiko. L\u2019incontro ha confermato l\u2019eccellente stato dei rapporti bilaterali nell\u2019anno del 160\u00b0 anniversario delle relazioni diplomatiche tra Italia e Giappone.<\/p>\n<p>Le due delegazioni hanno esaminato i profili di maggiore rilievo delle relazioni bilaterali, elevate al livello di partenariato strategico speciale lo scorso gennaio in occasione della visita del Presidente del Consiglio Meloni, e i principali temi relativi alla sicurezza globale. Al centro del colloquio anche la collaborazione nell\u2019industria della difesa, con particolare attenzione al partenariato GCAP tra Italia, Giappone e Regno Unito.<\/p>\n<p>Sono state infine approfondite le possibili sinergie in Africa tra il Piano Mattei e la Tokyo International Conference on African Development, alla luce dell\u2019esperienza di entrambi i Paesi nella cooperazione allo sviluppo e della riconosciuta competenza italiana in settori come la sicurezza alimentare e la riduzione del rischio di disastri.<\/p>\n","protected":false},"excerpt":{"rendered":"Il Vice Ministro degli Esteri Edmondo Cirielli ha ricevuto oggi alla Farnesina una delegazione del Senato giapponese guidata dal Sen. Aoki Kazuhiko. L\u2019incontro ha confermato l\u2019eccellente stato dei rapporti bilaterali nell\u2019anno del 160\u00b0 anniversario delle relazioni diplomatiche tra Italia e Giappone. Le due delegazioni hanno esaminato i profili di maggiore rilievo delle relazioni bilaterali, elevate [&hellip;]","protected":false},"author":34,"featured_media":203368,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[45,386],"class_list":["post-203367","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicati","tag-asia-e-oceania","tag-vice-ministro-edmondo-cirielli"],"_links":{"self":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/posts\/203367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=203367"}],"version-history":[{"count":1,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/posts\/203367\/revisions"}],"predecessor-version":[{"id":203370,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/posts\/203367\/revisions\/203370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/media\/203368"}],"wp:attachment":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=203367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/categories?post=203367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=203367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}