{"id":21107,"date":"2012-01-13T11:03:45","date_gmt":"2012-01-13T10:03:45","guid":{"rendered":"https:\/\/www.esteri.it\/sala_stampa\/archivionotizie\/comunicati\/2012\/01\/20120113_nigeria\/"},"modified":"2012-01-13T11:03:45","modified_gmt":"2012-01-13T10:03:45","slug":"20120113_nigeria","status":"publish","type":"post","link":"https:\/\/www.esteri.it\/it\/sala_stampa\/archivionotizie\/approfondimenti\/2012\/01\/20120113_nigeria\/","title":{"rendered":"Nigeria: corso per addetti di polizia doganale a Orvieto"},"content":{"rendered":"<p><P>Al via presso il Centro di Addestramento e Specializzazione della Guardia di Finanza (CAS) a Orvieto un corso per operatori della polizia doganale ed di frontiera della Repubblica Federale di Nigeria, della durata di tre settimane, in materia doganale e di controllo delle frontiere. Il corso, rivolto a 20 ufficiali e sottufficiali della polizia doganale e di frontiera, \u00e8 stato organizzato grazie alla collaborazione tra il Corpo e ed il MAE.<\/P><br \/>\n<P>Obiettivo del corso \u00e8 il rafforzamento delle capacit\u00e0 di controllo doganale in Nigeria: il progetto si propone, attraverso il modello di &#8220;formazione dei formatori&#8221;, di dotare la polizia doganale e di frontiera della Repubblica Federale di Nigeria di propri team di training per fornire un ulteriore contributo nell\u2019ottica del trasferimento ai nigeriani di maggiori responsabilit\u00e0.<\/P><br \/>\n<P>L\u2019attivit\u00e0 formativa, organizzata in moduli, fornir\u00e0 ai discenti una visione d&#8217;insieme approfondendo sia aspetti operativi che alla normativa internazionale in materia doganale. In particolare, il corso prevede sessioni, impartite dal personale della GdF, dedicate: al controllo delle persone, al controllo delle merci, al contrasto all\u2019immigrazione clandestina, al contrabbando, alla repressione dei traffici di armi e stupefacenti, alla vigilanza sulla sicurezza dei confini, alla tutela personale dell\u2019operatore, alle tecniche di tiro, alle tecniche operative di polizia. Sono previste inoltre conferenze, seminari e tre visite, presso un centro di addestramento di unit\u00e0 cinofile, il porto di Civitavecchia e presso l&#8217;aeroporto di Fiumicino.<\/P><br \/>\n<P>La &#8220;Sezione MAE&#8221; del II Reparto &#8211; URI del Comando Generale della Guardia di Finanza, inserita funzionalmente presso la Segreteria Generale \u2013 Unit\u00e0 di Coordinamento del MAE promuove forme di collaborazione con le Direzioni Generali attuando sinergie nei settori di rispettiva competenza. Questa collaborazione, nel comparto della formazione si \u00e8 concretizzata dal 2009 in undici corsi a favore di funzionari appartenenti a Forze di polizia e ad Agenzie di law enforcement operanti nel settore doganale dei seguenti Paesi: Libia Macedonia, Somalia, Afghanistan, Angola, Mali, Kenia, Mauritania e Mozambico numerosi corpi di polizia stranieri. I corsi, ad eccezione dei due svoltisi presso la Scuola Nautica della Guardia di Finanza di Gaeta, si sono tenuti presso la struttura di Addestramento e Specializzazione del Corpo ad Orvieto.<\/P><\/p>\n","protected":false},"excerpt":{"rendered":"Al via presso il Centro di Addestramento e Specializzazione della Guardia di Finanza (CAS) a Orvieto un corso per operatori della polizia doganale ed di frontiera della Repubblica Federale di Nigeria, della durata di tre settimane, in materia doganale e di controllo delle frontiere. Il corso, rivolto a 20 ufficiali e sottufficiali della polizia doganale [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[31],"class_list":["post-21107","post","type-post","status-publish","format-standard","hentry","category-approfondimenti","tag-africa"],"_links":{"self":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/posts\/21107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=21107"}],"version-history":[{"count":0,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/posts\/21107\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=21107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/categories?post=21107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=21107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}